{"id":1442,"date":"2016-03-09T11:23:43","date_gmt":"2016-03-09T10:23:43","guid":{"rendered":"https:\/\/www.fourniresto.com\/blog\/?p=1442"},"modified":"2022-03-11T11:56:43","modified_gmt":"2022-03-11T10:56:43","slug":"le-fast-good-manger-plus-sainement-et-rapidement","status":"publish","type":"post","link":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/","title":{"rendered":"Le &#8220;fast-good&#8221; : manger plus sainement et rapidement !"},"content":{"rendered":"<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1443\" src=\"https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/food-Favim.com-2685384.jpg\" alt=\"Fast Good\" width=\"500\" height=\"333\" srcset=\"https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/food-Favim.com-2685384.jpg 500w, https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/food-Favim.com-2685384-300x200.jpg 300w, https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/food-Favim.com-2685384-370x246.jpg 370w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/p>\n<p>Apr\u00e8s le slow food et le fast-food, aujourd&#8217;hui la tendance est au &#8220;<strong>fast-good<\/strong>&#8220;! !<\/p>\n<p>La tendance est au 100% bio et au sans gluten, on mange bio et sainement. Le fast-good arrive pour vous faciliter la vie ! L&#8217;intol\u00e9rance au gluten peut rendre votre vie tr\u00e8s difficile pour manger dans les restaurants et encore plus dans les fast-food. Aujourd&#8217;hui les attentes des consommateurs ont chang\u00e9, on veut manger mieux.<\/p>\n<p>Aujourd&#8217;hui, il est tr\u00e8s facile de manger rapidement avec les salad&#8217;bars, les sandwicheries, les take-away, les traditionnels fast-food, les rayons snacks dans les supermarch\u00e9s&#8230; les apports nutritifs restent toutefois limit\u00e9s. Et si on vous offrait&nbsp;la qualit\u00e9 et la rapidit\u00e9 ?<\/p>\n<p>Le <strong>&#8220;fast-good&#8221;&nbsp;<\/strong>arrive, vous trouverez d\u00e9sormais dans vos villes de plus en plus de restaurants\/snacks proposant des plats pr\u00e9par\u00e9s&nbsp;\u00e0 base de produits frais et authentiques. Aujourd&#8217;hui on prend \u00e0 emporter, la tendance snack bio est un concept en \u00e9volution. Il est d\u00e9sormais possible de manger &#8220;healthy&#8221; et rapidement !<\/p>\n<p>Les fran\u00e7ais sont fans des salad&#8217;bars et des &#8220;pasta bar&#8221; r\u00e9pondant aux nouvelles demandes&nbsp;de produits frais et go\u00fbteux. On compose sa salade rapidement avec des produits frais, on prend ses p\u00e2tes \u00e0 emporter&#8230; c&#8217;est le fast-good !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s le slow food et le fast-food, aujourd&#8217;hui la tendance est au &#8220;fast-good&#8220;! ! La tendance est au 100% bio et au sans gluten, on mange bio et sainement. Le&hellip;<\/p>\n","protected":false},"author":1,"featured_media":15688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_uag_custom_page_level_css":""},"categories":[905],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le &quot;fast-good&quot; : manger plus sainement et rapidement ! - Le Blog FourniResto<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le &quot;fast-good&quot; : manger plus sainement et rapidement ! - Le Blog FourniResto\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s le slow food et le fast-food, aujourd&#8217;hui la tendance est au &#8220;fast-good&#8220;! ! La tendance est au 100% bio et au sans gluten, on mange bio et sainement. Le&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Blog FourniResto\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-09T10:23:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-11T10:56:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2240\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/\",\"url\":\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/\",\"name\":\"Le \\\"fast-good\\\" : manger plus sainement et rapidement ! - Le Blog FourniResto\",\"isPartOf\":{\"@id\":\"https:\/\/www.fourniresto.com\/blog\/#website\"},\"datePublished\":\"2016-03-09T10:23:43+00:00\",\"dateModified\":\"2022-03-11T10:56:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.fourniresto.com\/blog\/#\/schema\/person\/7bdd27da86a0fd78ebae2c0282518b37\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fourniresto.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le &#8220;fast-good&#8221; : manger plus sainement et rapidement !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fourniresto.com\/blog\/#website\",\"url\":\"https:\/\/www.fourniresto.com\/blog\/\",\"name\":\"Le Blog FourniResto\",\"description\":\"Conseils et actualit\u00e9s sur la Restauration Professionnelle\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fourniresto.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fourniresto.com\/blog\/#\/schema\/person\/7bdd27da86a0fd78ebae2c0282518b37\",\"name\":\"Admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le \"fast-good\" : manger plus sainement et rapidement ! - Le Blog FourniResto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/","og_locale":"fr_FR","og_type":"article","og_title":"Le \"fast-good\" : manger plus sainement et rapidement ! - Le Blog FourniResto","og_description":"Apr\u00e8s le slow food et le fast-food, aujourd&#8217;hui la tendance est au &#8220;fast-good&#8220;! ! La tendance est au 100% bio et au sans gluten, on mange bio et sainement. Le&hellip;","og_url":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/","og_site_name":"Le Blog FourniResto","article_published_time":"2016-03-09T10:23:43+00:00","article_modified_time":"2022-03-11T10:56:43+00:00","og_image":[{"width":2240,"height":1260,"url":"https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement-.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Admin","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/","url":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/","name":"Le \"fast-good\" : manger plus sainement et rapidement ! - Le Blog FourniResto","isPartOf":{"@id":"https:\/\/www.fourniresto.com\/blog\/#website"},"datePublished":"2016-03-09T10:23:43+00:00","dateModified":"2022-03-11T10:56:43+00:00","author":{"@id":"https:\/\/www.fourniresto.com\/blog\/#\/schema\/person\/7bdd27da86a0fd78ebae2c0282518b37"},"breadcrumb":{"@id":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.fourniresto.com\/blog\/le-fast-good-manger-plus-sainement-et-rapidement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fourniresto.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Le &#8220;fast-good&#8221; : manger plus sainement et rapidement !"}]},{"@type":"WebSite","@id":"https:\/\/www.fourniresto.com\/blog\/#website","url":"https:\/\/www.fourniresto.com\/blog\/","name":"Le Blog FourniResto","description":"Conseils et actualit\u00e9s sur la Restauration Professionnelle","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fourniresto.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fourniresto.com\/blog\/#\/schema\/person\/7bdd27da86a0fd78ebae2c0282518b37","name":"Admin"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement-.jpg",2240,1260,false],"thumbnail":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--150x150.jpg",150,150,true],"medium":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--300x169.jpg",300,169,true],"medium_large":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement-.jpg",768,432,false],"large":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--1024x576.jpg",1024,576,true],"1536x1536":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--1536x864.jpg",1536,864,true],"2048x2048":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--2048x1152.jpg",2048,1152,true],"ms_image_size_300":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--300x200.jpg",300,200,true],"post-thumbnail":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x208.jpg",370,208,true],"especio-thumb-huge":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--1170x658.jpg",1170,658,true],"especio-thumb-big":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--760x428.jpg",760,428,true],"especio-thumb-med":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x208.jpg",370,208,true],"especio-thumb-tiny":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--135x135.jpg",135,135,true],"especio-thumb-masonry-big":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--760x428.jpg",760,428,true],"especio-thumb-masonry":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x208.jpg",370,208,true],"especio-thumb-extra":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--570x498.jpg",570,498,true],"especio-thumb-square":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--270x258.jpg",270,258,true],"especio-thumb-plain":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--218x162.jpg",218,162,true],"especio-thumb-list":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x275.jpg",370,275,true],"trx_addons-thumb-small":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--270x152.jpg",270,152,true],"trx_addons-thumb-portrait":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x493.jpg",370,493,true],"trx_addons-thumb-avatar":["https:\/\/www.fourniresto.com\/blog\/wp-content\/uploads\/2016\/03\/Le-fast-good-manger-plus-sainement-et-rapidement--370x370.jpg",370,370,true]},"uagb_author_info":{"display_name":"Admin","author_link":"https:\/\/www.fourniresto.com\/blog\/author\/admin\/"},"uagb_comment_info":0,"uagb_excerpt":"Apr\u00e8s le slow food et le fast-food, aujourd&#8217;hui la tendance est au &#8220;fast-good&#8220;! ! La tendance est au 100% bio et au sans gluten, on mange bio et sainement. Le&hellip;","_links":{"self":[{"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/posts\/1442"}],"collection":[{"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/comments?post=1442"}],"version-history":[{"count":4,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/posts\/1442\/revisions"}],"predecessor-version":[{"id":15083,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/posts\/1442\/revisions\/15083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/media\/15688"}],"wp:attachment":[{"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/media?parent=1442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/categories?post=1442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fourniresto.com\/blog\/wp-json\/wp\/v2\/tags?post=1442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}